{"id":15788,"date":"2015-06-04T21:50:43","date_gmt":"2015-06-05T01:50:43","guid":{"rendered":"https:\/\/dev.stephenlow.com\/le-tournage-de-rescue-3d\/"},"modified":"2015-06-04T21:50:43","modified_gmt":"2015-06-05T01:50:43","slug":"le-tournage-de-rescue-3d","status":"publish","type":"post","link":"https:\/\/www.stephenlow.com\/fr\/le-tournage-de-rescue-3d\/","title":{"rendered":"Le tournage de <em>Rescue 3D<\/em>"},"content":{"rendered":"<h2>Un portrait d&#8217;une intervention en cas de catastrophe<\/h2>\n<p>Film\u00e9 pour \u00eatre pr\u00e9sent\u00e9 en IMAX 3D et 2D, <em>Rescue<\/em> plonge le public dans le travail difficile, mais inspirant, qui consiste \u00e0 sauver des vies face \u00e0 une catastrophe naturelle. Ce projet de documentaire est parti d&#8217;une approche simple, bien que difficile : suivre la formation d&#8217;individus \u00e0 l&#8217;intervention en cas de catastrophe, puis les suivre lorsqu&#8217;ils interviennent lors d&#8217;une v\u00e9ritable catastrophe. Mais quels sont les individus et les organisations qui pourraient \u00eatre amen\u00e9s \u00e0 intervenir, et quelle est la crise&nbsp;\u00e0 laquelle ils pourraient \u00eatre confront\u00e9s ? L&#8217;\u00e9quipe de production pouvait-elle \u00eatre pr\u00eate \u00e0 filmer une catastrophe en cours ? Les r\u00e9alisateurs savaient avant de commencer qu&#8217;il s&#8217;agirait d&#8217;un documentaire tr\u00e8s fluide, \u00e9voluant au gr\u00e9 des opportunit\u00e9s \u00e9mergentes et des catastrophes inconnues.<\/p>\n<div id=\"attachment_2334\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX384661.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2334\" class=\"wp-image-2334 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX384661-1024x483.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"483\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX384661-1024x483.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX384661-300x142.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX384661-1080x510.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2334\" class=\"wp-caption-text\">Tournage depuis la baie d&#8217;h\u00e9licopt\u00e8re du destroyer de la marine canadienne NCSM Athabaskan.<\/p><\/div>\n<p>Les r\u00e9alisateurs de <em>Rescue<\/em> ont d\u00fb faire des choix difficiles quant \u00e0 la mani\u00e8re de centrer le film et d&#8217;obtenir des images qui racontent une histoire passionnante sur les personnes qui r\u00e9pondent \u00e0 l&#8217;appel lorsqu&#8217;une catastrophe survient. La r\u00e9ponse \u00e0 une catastrophe&nbsp;implique in\u00e9vitablement un grand nombre de personnes et d&#8217;organisations de sp\u00e9cialit\u00e9s et de capacit\u00e9s diff\u00e9rentes. Aucun groupe ne dispose \u00e0 lui seul des ressources et de l&#8217;expertise n\u00e9cessaires pour r\u00e9pondre \u00e0 tous les besoins profonds des communaut\u00e9s touch\u00e9es par une catastrophe majeure. Les acteurs militaires disposent du mat\u00e9riel, de la formation, de la mobilit\u00e9 et de la structure organisationnelle n\u00e9cessaires pour r\u00e9agir rapidement aux catastrophes dans les zones recul\u00e9es, en jouant le r\u00f4le de techniciens du sauvetage et en aidant \u00e0 maintenir l&#8217;ordre dans les communaut\u00e9s et les pays fragment\u00e9s par la catastrophe. Les agences civiles et les organisations non gouvernementales apportent une forte orientation humanitaire, une perspective internationale, une capacit\u00e9 \u00e0 solliciter des ressources aupr\u00e8s de la communaut\u00e9 internationale, une exp\u00e9rience dans le soutien et la gestion des r\u00e9fugi\u00e9s ainsi qu&#8217;une vision \u00e0 plus long terme du red\u00e9veloppement.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-15788 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX661564.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX661564-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-14504\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-14504'>\n\t\t\t\tMajor Matt Jonkey, US National Guard\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX696281.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX696281-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-14521\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX696281-150x150.jpg 150w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX696281-680x675.jpg 680w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-14521'>\n\t\t\t\tCaptain Lauren Ross, US Air Force\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-14511\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-14511'>\n\t\t\t\tSteve Heicklen, volunteer fire fighter and rescue coordinator\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Le film final&nbsp;<em>Rescue<\/em> est un voyage dans le monde r\u00e9el de la catastrophe et de l&#8217;intervention d&#8217;urgence, captur\u00e9 (en 3D) avec une ampleur et un impact sans pr\u00e9c\u00e9dent pour \u00e9cran g\u00e9ant. Dans les coulisses, le film suit un commandant de la marine canadienne, deux pilotes et un technicien de sauvetage b\u00e9n\u00e9vole qui s&#8217;entra\u00eenent \u00e0 l&#8217;action. Lorsqu&#8217;un tremblement de terre frappe Ha\u00efti, provoquant l&#8217;une des plus grandes catastrophes humanitaires du si\u00e8cle, le public est entra\u00een\u00e9 dans l&#8217;effort massif qui r\u00e9unit des intervenants militaires et civils et du mat\u00e9riel du monde entier.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h2>Vers la production<\/h2>\n<p><em>Rescue<\/em> a \u00e9t\u00e9 tourn\u00e9 dans l&#8217;Atlantique Nord, \u00e0 Halifax, \u00e0 Montr\u00e9al, en Californie, au Nevada et en Ha\u00efti apr\u00e8s le tremblement de terre de 2010.&nbsp; La production a d\u00e9but\u00e9 par le tournage d&#8217;actions a\u00e9riennes et navales mettant en sc\u00e8ne certains des \u00e9quipements g\u00e9n\u00e9ralement utilis\u00e9s dans les interventions en cas de catastrophe majeure : avions de transport C-17, h\u00e9licopt\u00e8res Chinook \u00e0 deux rotors et navires de la marine.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-15788 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-2-14293\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-2-14293'>\n\t\t\t\tA C-17 transport jet tackles a rough landing in a scene from the giant screen film &#8220;Rescue&#8221;.\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_11243-pano.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_11243-pano-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0016545.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0016545-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX404916.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX404916-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<div id=\"attachment_2394\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_980651.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2394\" class=\"wp-image-2394 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_980651-1024x683.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_980651-1024x683.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_980651-300x200.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_980651-1080x720.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2394\" class=\"wp-caption-text\">Tournage de la fr\u00e9gate de la marine canadienne NCSM Halifax dans une mer agit\u00e9e de l&#8217;Atlantique.<\/p><\/div>\n<div id=\"attachment_2327\" style=\"width: 801px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2327\" class=\"wp-image-2327 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611-791x1024.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"791\" height=\"1024\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611-791x1024.jpg 791w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611-232x300.jpg 232w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611-1080x1398.jpg 1080w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX312611.jpg 1970w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/><\/a><p id=\"caption-attachment-2327\" class=\"wp-caption-text\">L&#8217;\u00e9quipe de production filme sur le pont d&#8217;envol du NCSM Athabaskan. Au premier plan, de gauche \u00e0 droite : Philippe Prud&#8217;homme (1er assistant cam\u00e9raman) ; Marc Poirier (directeur de la photographie) ; Stephen Low (r\u00e9alisateur).<\/p><\/div>\n<p>Neuf jours en mer dans l&#8217;Atlantique Nord avec la marine canadienne lors d&#8217;un entra\u00eenement de la mer d&#8217;Irlande \u00e0 Halifax ont permis \u00e0 l&#8217;\u00e9quipe de production de se familiariser avec les op\u00e9rations navales en haute mer. L&#8217;\u00e9quipe occupait des postes \u00e0 bord du destroyer NCSM Athabaskan, sous les ordres du capitaine de fr\u00e9gate Peter Crane. L&#8217;\u00e9quipe a tout couvert, des exercices d&#8217;homme \u00e0 la mer aux interventions m\u00e9dicales d&#8217;urgence.<\/p>\n<div id=\"attachment_2330\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX357941.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2330\" class=\"wp-image-2330 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX357941-1024x679.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"679\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX357941-1024x679.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX357941-300x199.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX357941-1080x716.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2330\" class=\"wp-caption-text\">Le NCSM Athabaskan est ravitaill\u00e9 en mer par le navire ravitailleur Protecteur.<\/p><\/div>\n<p>Par une co\u00efncidence remarquable, c&#8217;est le NCSM Athabaskan, sous la direction de M. Crane, et la fr\u00e9gate NCSM Halifax qui allaient \u00eatre envoy\u00e9s quelques semaines plus tard pour r\u00e9pondre au tremblement de terre d&#8217;Ha\u00efti et \u00e0 la crise humanitaire massive qui s&#8217;ensuivait. L&#8217;\u00e9quipe de tournage suivra.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h2>Tremblement de terre en Ha\u00efti<\/h2>\n<p><strong>En route vers la catastrophe.<\/strong> L&#8217;\u00e9quipe de production est arriv\u00e9e sur place le 2 f\u00e9vrier 2010, deux semaines apr\u00e8s le premier tremblement de terre. La situation sur le terrain \u00e9tait encore fluctuante et dangereuse.<\/p>\n\n\t\t<style>\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-15788 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<div id=\"attachment_2409\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-P103082637.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2409\" class=\"wp-image-2409 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-P103082637.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"576\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-P103082637.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-P103082637-300x169.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2409\" class=\"wp-caption-text\">Les d\u00e9combres de Port-au-Prince, Ha\u00efti depuis l&#8217;h\u00e9licopt\u00e8re de production. Janvier 2012.<\/p><\/div>\n<p><strong>L&#8217;\u00e9quipe.<\/strong> Par rapport aux \u00e9quipes conventionnelles, filmant dans une situation telle que les cons\u00e9quences du tremblement de terre en Ha\u00efti, o\u00f9 vous auriez peut-\u00eatre une \u00e9quipe de 2 ou 3 personnes, pour IMAX\u00ae 3D, une \u00e9quipe de neuf personnes a \u00e9t\u00e9 n\u00e9cessaire. La cam\u00e9ra elle-m\u00eame n\u00e9cessite plus de personnel, pour le montage, etc. Il y avait \u00e9galement du mat\u00e9riel d&#8217;\u00e9clairage, bien que minime compte tenu de la situation, et tout ce mat\u00e9riel devait \u00eatre mobile. Lors du tournage d&#8217;un film en st\u00e9r\u00e9oscopie, de nombreux \u00e9l\u00e9ments sont doubl\u00e9s : il faut charger deux chargeurs de film au lieu d&#8217;un et transporter deux fois plus de pellicule \u00e0 tout moment.<\/p>\n<p><strong>Pr\u00e9paration.<\/strong> Pour \u00e9laborer un plan d&#8217;action avant le d\u00e9part, la production a pass\u00e9 au crible des informations provenant d&#8217;un large \u00e9ventail de sources telles que le Programme alimentaire mondial, l&#8217;ONU, diverses ONG et des sources en ligne et a \u00e9tabli des contacts pr\u00e9alables avec la marine canadienne et l&#8217;arm\u00e9e de l&#8217;air am\u00e9ricaine. Mais ces informations \u00e9taient in\u00e9vitablement incompl\u00e8tes, la situation r\u00e9elle sur le terrain en Ha\u00efti \u00e9tait tout simplement trop chaotique.<\/p>\n<div id=\"attachment_1130\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1130\" class=\"wp-image-1130 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0033549-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1130\" class=\"wp-caption-text\">Ha\u00efti apr\u00e8s le tremblement de terre. Une image tir\u00e9e du film <em>Rescue<\/em>.<\/p><\/div>\n<p><strong>O\u00f9 aller?<\/strong> L&#8217;\u00e9quipe de production ne voulait pas se rendre au c\u0153ur de la catastrophe, o\u00f9 elle aurait pu contribuer \u00e0 la confusion, voire s&#8217;enliser et \u00eatre incapable de fonctionner. Il a donc fallu d\u00e9cider o\u00f9 aller en Ha\u00efti et comment s&#8217;y rendre. Il a \u00e9t\u00e9 d\u00e9cid\u00e9 de ne pas prendre le bateau. L&#8217;\u00e9quipe est donc pass\u00e9e par la R\u00e9publique dominicaine. Avec l&#8217;aide d&#8217;une soci\u00e9t\u00e9 de production sur place \u00e0 Barahona en R\u00e9publique dominicaine, l&#8217;\u00e9quipe a pu organiser la logistique de l&#8217;h\u00e9bergement, des v\u00e9hicules et de l&#8217;entr\u00e9e en Ha\u00efti.&nbsp;Les navires de la marine canadienne sur lesquels l&#8217;\u00e9quipe avait tourn\u00e9 avaient \u00e9t\u00e9 envoy\u00e9s \u00e0 Jacmel, en Ha\u00efti,&nbsp;et il a donc \u00e9t\u00e9 d\u00e9cid\u00e9 que Jacmel serait la premi\u00e8re destination de l&#8217;\u00e9quipe. \u00c0 partir de l\u00e0, ils ont d\u00fb improviser.<\/p>\n<div id=\"attachment_1122\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0010241.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1122\" class=\"wp-image-1122 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0010241-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0010241-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0010241-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0010241-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1122\" class=\"wp-caption-text\">Image tir\u00e9e du film <em>Rescue<\/em><\/p><\/div>\n<p>L&#8217;arriv\u00e9e en Ha\u00efti, un pays dont les infrastructures sont pratiquement inexistantes, a \u00e9t\u00e9 v\u00e9cue comme une arriv\u00e9e dans une zone de guerre. La pr\u00e9sence d&#8217;un grand nombre de militaires et d&#8217;\u00e9quipements du monde entier dans le cadre des op\u00e9rations de sauvetage, ainsi que la pr\u00e9sence de b\u00e2timents en ruine semblant avoir \u00e9t\u00e9 bombard\u00e9s, ont contribu\u00e9 \u00e0 donner l&#8217;impression d&#8217;une zone de guerre.<\/p>\n<div id=\"attachment_1120\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0001039.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1120\" class=\"wp-image-1120 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0001039-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0001039-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0001039-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0001039-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1120\" class=\"wp-caption-text\">Les convois de ravitaillement convergent vers la r\u00e9gion touch\u00e9e autour de Port-au-Prince.<\/p><\/div>\n<div id=\"attachment_1121\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0005840.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1121\" class=\"wp-image-1121 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0005840-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0005840-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0005840-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0005840-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1121\" class=\"wp-caption-text\">L&#8217;USNS Comfort a jet\u00e9 l&#8217;ancre au large d&#8217;Ha\u00efti en janvier 2010. Au lendemain du s\u00e9isme, le navire-h\u00f4pital a soign\u00e9 quelque 1 000 bless\u00e9s ha\u00eftiens et effectu\u00e9 850 interventions chirurgicales.<\/p><\/div>\n<p>L&#8217;\u00e9quipe de production ne voulait pas s&#8217;imposer en Ha\u00efti, alors que la r\u00e9gion \u00e9tait d\u00e9j\u00e0 \u00e0 court de ressources. Il a \u00e9t\u00e9 d\u00e9cid\u00e9 que l&#8217;\u00e9quipe resterait en R\u00e9publique dominicaine et que tout le monde arriverait et repartirait chaque jour en h\u00e9licopt\u00e8re, pour se retrouver \u00e0 un endroit convenu \u00e0 l&#8217;avance en Ha\u00efti avec un camion-plateau, lou\u00e9 \u00e0 une entreprise de camionnage locale (qui \u00e9tait compl\u00e8tement au ch\u00f4mage \u00e0 cause du tremblement de terre). Ce camion plat a servi de camp de base mobile \u00e0 la production pendant la p\u00e9riode pass\u00e9e en Ha\u00efti. Un guide parlant cr\u00e9ole a \u00e9galement \u00e9t\u00e9 engag\u00e9.<\/p>\n<p>Le guide les a emmen\u00e9s dans les environs et ils ont suivi le &#8220;nez&#8221; du r\u00e9alisateur Stephen Low, son instinct pour trouver les bons moments \u00e0 filmer. Stephen ne cherchait rien de sanglant ou de choquant. Il voulait montrer l&#8217;ampleur de la catastrophe et l&#8217;aide apport\u00e9e par les ONG et les arm\u00e9es du monde entier.<\/p>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0356131.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-2390 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0356131-1024x768.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0356131-1024x768.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0356131-300x225.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0356131-1080x810.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Chaque jour, l&#8217;\u00e9quipe apportait une glaci\u00e8re avec de la nourriture, des biscuits, des barres de c\u00e9r\u00e9ales, etc., mais elle estimait qu&#8217;elle ne pouvait tout simplement pas manger devant ses chauffeurs et les autres Ha\u00eftiens, elle donna donc toute la nourriture, \u00e0 l&#8217;exception d&#8217;un peu d&#8217;eau. Ils se sont sentis mal \u00e0 l&#8217;aise de &#8220;s&#8217;empiffrer&#8221; en voyant ce qui se passait. Les membres de l&#8217;\u00e9quipage sont revenus profond\u00e9ment perturb\u00e9s et boulevers\u00e9s. Ils sont revenus avec beaucoup de souvenirs troublants.<\/p>\n<p>L&#8217;\u00e9quipe de tournage a d\u00e9coll\u00e9 de Barahona pour se rendre dans un petit a\u00e9roport pr\u00e8s de Jacmel, o\u00f9 elle rencontrait quotidiennement les chauffeurs et les guides ha\u00eftiens. C&#8217;\u00e9tait un petit a\u00e9roport en ruine. Le premier jour de tournage, l&#8217;\u00e9quipe s&#8217;est mise en contact avec l&#8217;\u00e9quipe canadienne d&#8217;intervention en cas de catastrophe (DART). \u00c0 partir de l\u00e0, la production a suivi ce qui se pr\u00e9sentait ou semblait int\u00e9ressant, par exemple la visite d&#8217;un orphelinat reconstruit par la marine canadienne. L&#8217;improvisation quotidienne \u00e9tait essentielle.<\/p>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111.jpg\"><img decoding=\"async\" class=\"alignleft wp-image-2389 size-medium\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111-300x200.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111-300x200.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111-1024x683.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0313111-1080x720.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>En Ha\u00efti, les communications \u00e9taient tr\u00e8s limit\u00e9es et l&#8217;\u00e9quipe se trouvait souvent dans l&#8217;obscurit\u00e9 pendant la journ\u00e9e. Ils sont rest\u00e9s en contact par l&#8217;interm\u00e9diaire de la base principale en R\u00e9publique dominicaine, o\u00f9 ils retournaient chaque nuit, pour prendre des nouvelles de la soci\u00e9t\u00e9 de production \u00e0 Montr\u00e9al. Par exemple, ils recevaient en R\u00e9publique dominicaine un message transf\u00e9r\u00e9 d&#8217;Ottawa, envoy\u00e9 depuis l&#8217;Athabaskan, indiquant que la marine \u00e9tait pr\u00eate \u00e0 accueillir l&#8217;\u00e9quipe de tournage et \u00e0 lui faire visiter L\u00e9og\u00e2ne. Pour une raison ou une autre, les messages sur Blackberry fonctionnaient, mais pas sur les t\u00e9l\u00e9phones cellulaires. M\u00eame les militaires ont d\u00e9clar\u00e9 que les SMS \u00e9taient leur principal moyen de communication ! Autant dire que les communications \u00e9taient un peu compliqu\u00e9es. Il en a \u00e9t\u00e9 de m\u00eame pour les contacts avec l&#8217;arm\u00e9e am\u00e9ricaine et l&#8217;arm\u00e9e de l&#8217;air. Les coproducteurs de K2 (bas\u00e9s aux \u00c9tats-Unis) recevaient des nouvelles du 82e r\u00e9giment a\u00e9roport\u00e9 de Los Angeles, qui \u00e9taient transmises \u00e0 destination de la R\u00e9publique dominicaine, puis l&#8217;\u00e9quipe de tournage s&#8217;organisait pour se rendre en h\u00e9licopt\u00e8re \u00e0 la rencontre du 82e r\u00e9giment.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<p>&nbsp;<\/p>\n<h2>Prendre l&#8217;air<\/h2>\n<p>\n\t\t<style>\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-4' class='gallery galleryid-15788 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_020031.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_020031-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_009936.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_009936-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-Rescue_838.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-Rescue_838-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_019530.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_019530-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<br \/>\nL&#8217;acquisition d&#8217;un h\u00e9licopt\u00e8re a \u00e9t\u00e9 une t\u00e2che difficile en soi. Tout d&#8217;abord, la monture Spacecam ne s&#8217;adapte pas \u00e0 n&#8217;importe quel h\u00e9licopt\u00e8re. Or, de nombreux h\u00e9licopt\u00e8res de la r\u00e9gion imm\u00e9diate d&#8217;Ha\u00efti \u00e9taient utilis\u00e9s pour des op\u00e9rations de sauvetage. La production a fini par trouver un h\u00e9licopt\u00e8re ad\u00e9quat \u00e0 Porto Rico, et a donc d\u00fb faire voler la Spacecam de Los Angeles \u00e0 Porto Rico, puis l&#8217;h\u00e9licopt\u00e8re a d\u00fb faire de courtes escales de ravitaillement pour atteindre Ha\u00efti. Ils ont tourn\u00e9 pendant quatre jours en utilisant&nbsp;la Spacecam mont\u00e9e sur l&#8217;h\u00e9licopt\u00e8re, avec le r\u00e9alisateur \u00e0 bord. Pendant ce temps, le reste de l&#8217;\u00e9quipe de tournage \u00e0 Barahona se pr\u00e9parait \u00e0 tourner sur le terrain \u00e0 Jacmel.<\/p>\n<div id=\"attachment_3823\" style=\"width: 1034px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-271.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3823\" class=\"size-full wp-image-3823\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-271.jpg\" alt=\"Le syst\u00e8me Spacecam est mont\u00e9 sur un h\u00e9licopt\u00e8re Aerostar achet\u00e9 au Costa Rica pour le tournage.\" width=\"1024\" height=\"921\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-271.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-271-300x270.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3823\" class=\"wp-caption-text\">Le syst\u00e8me Spacecam est mont\u00e9 sur un h\u00e9licopt\u00e8re Aerostar achet\u00e9 au Costa Rica pour le tournage.<\/p><\/div>\n<p><img decoding=\"async\" class=\" size-full wp-image-2386 alignnone\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_020031.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_020031.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_020031-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Pour obtenir l&#8217;autorisation de voler dans l&#8217;espace a\u00e9rien ha\u00eftien, l&#8217;unit\u00e9 militaire am\u00e9ricaine SOUTHCOM a d\u00fb \u00eatre contact\u00e9e. Le SOUTHCOM \u00e9tait charg\u00e9 de cette mission \u00e0 la demande du gouvernement ha\u00eftien. Leur r\u00e9ponse \u00e0 l&#8217;\u00e9quipe de production a \u00e9t\u00e9 la suivante : entrez et improvisez ! C&#8217;\u00e9tait une libert\u00e9 totale. Il fallait faire attention aux radars, aux avions errants. l fallait observer \u00e0 l&#8217;\u0153il nu. Les collisions en vol \u00e9taient un r\u00e9el probl\u00e8me&#8230; et l&#8217;h\u00e9licopt\u00e8re devait fr\u00e9quemment se rendre \u00e0 Port-au-Prince pour se r\u00e9approvisionner en carburant.<\/p>\n<p>Le tournage des images de la&nbsp;Spacecam a permis \u00e0 l&#8217;\u00e9quipe de se faire une id\u00e9e de ce qui se passait et de d\u00e9terminer la route \u00e0 suivre pour la suite du tournage. Les images a\u00e9riennes ont \u00e9galement permis d&#8217;obtenir un enregistrement extraordinaire et d\u00e9taill\u00e9, en haute fid\u00e9lit\u00e9, de la catastrophe et de son impact sur la r\u00e9gion.<\/p>\n<div id=\"attachment_1132\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1132\" class=\"wp-image-1132 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0109951-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1132\" class=\"wp-caption-text\">Cath\u00e9drale qui s\u2019est effondr\u00e9e, image tir\u00e9e du film <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1129\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0029948.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1129\" class=\"wp-image-1129 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0029948-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0029948-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0029948-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0029948-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1129\" class=\"wp-caption-text\">Image tir\u00e9e du film sur \u00e9cran g\u00e9ant <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1128\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0027547.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1128\" class=\"wp-image-1128 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0027547-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0027547-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0027547-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0027547-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1128\" class=\"wp-caption-text\">Image tir\u00e9e du film sur \u00e9cran g\u00e9ant <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1127\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1127\" class=\"wp-image-1127 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0023546-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1127\" class=\"wp-caption-text\">Incendie incontr\u00f4lable sur une sc\u00e8ne de <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1125\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0015144.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1125\" class=\"wp-image-1125 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0015144-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0015144-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0015144-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0015144-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1125\" class=\"wp-caption-text\">Une sc\u00e8ne tir\u00e9e du film <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_3807\" style=\"width: 216px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G91L.127135633-crp.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3807\" class=\"wp-image-3807 size-medium\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G91L.127135633-crp-206x300.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"206\" height=\"300\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G91L.127135633-crp-206x300.jpg 206w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G91L.127135633-crp-704x1024.jpg 704w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G91L.127135633-crp.jpg 886w\" sizes=\"(max-width: 206px) 100vw, 206px\" \/><\/a><p id=\"caption-attachment-3807\" class=\"wp-caption-text\">Image tir\u00e9e du film sur \u00e9cran g\u00e9ant &#8220;Rescue&#8221;<\/p><\/div>\n<div id=\"attachment_3824\" style=\"width: 886px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3824\" class=\"wp-image-3824 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160-876x1024.jpg\" alt=\"Des secouristes s'occupent d'un enfant bless\u00e9. (Steven Heicklen au centre).\" width=\"876\" height=\"1024\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160-876x1024.jpg 876w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160-257x300.jpg 257w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160-1080x1263.jpg 1080w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0160.jpg 1642w\" sizes=\"(max-width: 876px) 100vw, 876px\" \/><\/a><p id=\"caption-attachment-3824\" class=\"wp-caption-text\">Des secouristes s&#8217;occupent d&#8217;un enfant bless\u00e9. (Steven Heicklen au centre).<\/p><\/div>\n<p>C&#8217;est lors de l&#8217;un de ces ravitaillements que l&#8217;\u00e9quipe de tournage a rencontr\u00e9 Stephen Heicklen, un responsable b\u00e9n\u00e9vole des situations d&#8217;urgence ayant d\u00e9j\u00e0 v\u00e9cu un certain nombre de catastrophes. Par la force de sa personnalit\u00e9, Heicklen a pris en stop l&#8217;h\u00e9licopt\u00e8re de la production pour se rendre \u00e0 Port-au-Prince. Il a &#8220;d\u00e9tourn\u00e9&#8221; l&#8217;\u00e9quipe du documentaire, ce qui a \u00e9t\u00e9 une chance ; ils l&#8217;ont ensuite film\u00e9 en train d&#8217;organiser une \u00e9vacuation m\u00e9dicale, et Heicklen est devenu l&#8217;un des principaux personnages du film, un exemple de film documentaire, un v\u00e9ritable travail en cours. En m\u00eame temps, la production ne s&#8217;est pas content\u00e9e de documenter la catastrophe depuis les coulisses, mais a contribu\u00e9 \u00e0 l&#8217;effort de secours en faisant don de son h\u00e9licopt\u00e8re pour transporter les victimes du tremblement de terre.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<p>&nbsp;<\/p>\n<h2>Formation en cas de catastrophe<\/h2>\n<p>Au-del\u00e0 des semaines pass\u00e9es en Ha\u00efti \u00e0 couvrir les cons\u00e9quences imm\u00e9diates du tremblement de terre, l&#8217;\u00e9quipe de production a film\u00e9 une vari\u00e9t\u00e9 d&#8217;activit\u00e9s de formation li\u00e9es au travail des personnes pr\u00e9sent\u00e9es dans le film.<\/p>\n<h3>Les sauveteurs<\/h3>\n<p>D\u00e8s le d\u00e9but de <em>Rescue<\/em>, nous faisons connaissance avec les personnalit\u00e9s du film et sommes plong\u00e9s dans leur remarquable entra\u00eenement, en mer, dans les airs et au sol, d\u00e9couvrant ainsi leurs origines, leurs passe-temps et leurs motivations. Le film suit l&#8217;histoire de quatre personnalit\u00e9s principales : Le commandant de la marine canadienne Peter Crain du NCSM Athabaskan ; le capitaine de l&#8217;arm\u00e9e de l&#8217;air am\u00e9ricaine Lauren Ross, pilote d&#8217;un avion de transport militaire C-17 ; le major de l&#8217;arm\u00e9e am\u00e9ricaine Matthew Jonkey, pilote d&#8217;un h\u00e9licopt\u00e8re CH-47 ; et Steven Heicklen, gestionnaire b\u00e9n\u00e9vole des situations d&#8217;urgence.<\/p>\n<div id=\"attachment_1157\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1157\" class=\"wp-image-1157 size-medium\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-300x191.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-1024x653.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-1080x688.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1157\" class=\"wp-caption-text\">Le commandant Peter Crane dans une sc\u00e8ne de <em>Rescue<\/em>.<\/p><\/div>\n<p>Le capitaine de fr\u00e9gate <strong>Peter Crain<\/strong> est le capitaine d&#8217;un destroyer de la Marine canadienne (NCSM Athabaskan), une affectation de choix pour ce marin de carri\u00e8re qui a grandi sur des bateaux, mais n&#8217;a jamais appris \u00e0 nager. Pour M. Crain, il s&#8217;agit d&#8217;une carri\u00e8re qui l&#8217;a amen\u00e9 \u00e0 parcourir le monde, \u00e0 surveiller les mers et \u00e0 prot\u00e9ger les c\u00f4tes. Pour Crain, chaque jour dans la marine a \u00e9t\u00e9 une aventure.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<div id=\"attachment_2396\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_272748.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2396\" class=\"wp-image-2396 size-medium\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_272748-300x200.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_272748-300x200.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_272748.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-2396\" class=\"wp-caption-text\">Le capitaine Lauren Ross.<\/p><\/div>\n<p>Capitaine <strong>Lauren Ross<\/strong>, jeune pilote d&#8217;un C-17 Globemaster II de l&#8217;arm\u00e9e de l&#8217;air am\u00e9ricaine, a fait le tour du monde avec son avion dans le cadre de diverses missions. Aux commandes de l&#8217;avion de transport g\u00e9ant, elle r\u00e9alise un r\u00eave d&#8217;enfant et suit les traces de son p\u00e8re et de son grand-p\u00e8re.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<div id=\"attachment_2363\" style=\"width: 304px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2363\" class=\"wp-image-2363 size-medium\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671-294x300.jpg\" alt=\"Steven Heicklen est un entrepreneur en b\u00e9ton aux multiples talents et un pompier volontaire\" width=\"294\" height=\"300\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671-294x300.jpg 294w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX667671.jpg 1002w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/><\/a><p id=\"caption-attachment-2363\" class=\"wp-caption-text\">Steven Heicklen est un entrepreneur en b\u00e9ton aux multiples talents et un pompier volontaire<\/p><\/div>\n<p><strong>Steven Heicklen<\/strong> est un entrepreneur en b\u00e9ton aux multiples talents et un pompier volontaire qui construit des piscines pour gagner sa vie, mais qui, en r\u00e9pondant \u00e0 des incendies et \u00e0 des catastrophes dans son pays et \u00e0 l&#8217;\u00e9tranger, a d\u00e9couvert de nouvelles d\u00e9bouch\u00e9es pour ses talents de gestionnaire et ses comp\u00e9tences en mati\u00e8re de b\u00e9ton et d&#8217;\u00e9quipement d&#8217;excavation lourd.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX658362.jpg\"><img decoding=\"async\" class=\" wp-image-2354 size-medium alignleft\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX658362-199x300.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX658362-199x300.jpg 199w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX658362.jpg 680w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p>Le major <strong>Matt Jonkey<\/strong> est un pilote d&#8217;h\u00e9licopt\u00e8re Chinook (CH-47) de la Garde nationale de l&#8217;arm\u00e9e du Nevada, qui a quitt\u00e9 son pays et s&#8217;est engag\u00e9 dans l&#8217;arm\u00e9e pour faire quelque chose de sa vie et n&#8217;a jamais regard\u00e9 en arri\u00e8re. Aujourd&#8217;hui, il forme d&#8217;autres personnes aux comp\u00e9tences uniques de l&#8217;\u00e9quipage d&#8217;h\u00e9licopt\u00e8res g\u00e9ants \u00e0 deux rotors et \u00e0 l&#8217;accomplissement de missions difficiles, telles que les atterrissages sur l&#8217;eau et dans le d\u00e9sert et les sauvetages en haute altitude d&#8217;alpinistes bless\u00e9s.<\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h3>Sauvetage a\u00e9rien<\/h3>\n<div id=\"attachment_2398\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_280350.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2398\" class=\"wp-image-2398 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_280350.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_280350.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_280350-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2398\" class=\"wp-caption-text\">L&#8217;h\u00e9licopt\u00e8re \u00e9quip\u00e9 de la Spacecam de la production plane au-dessus d&#8217;un C-17 Globemaster pendant le tournage de <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1133\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_3_0000014.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1133\" class=\"wp-image-1133 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_3_0000014-1024x756.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"756\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_3_0000014-1024x756.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_3_0000014-300x221.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_3_0000014-1080x797.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1133\" class=\"wp-caption-text\">D\u00e9collage et atterrissage de C-17 dans le d\u00e9sert du Nevada.<\/p><\/div>\n<div id=\"attachment_1134\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1134\" class=\"wp-image-1134 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015-1024x756.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"756\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015-1024x756.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015-300x221.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_ARRI_8_0000015-1080x797.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1134\" class=\"wp-caption-text\">Dans le d\u00e9sert.<\/p><\/div>\n<div id=\"attachment_1123\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0013742.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1123\" class=\"wp-image-1123 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0013742-1024x747.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0013742-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0013742-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-0013742-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1123\" class=\"wp-caption-text\">Embarquement des personnes \u00e9vacu\u00e9es. Un C-17 Globemaster de l&#8217;arm\u00e9e de l&#8217;air canadienne sur le tarmac de l&#8217;a\u00e9roport international Toussaint Lourverture, pr\u00e8s de Port-au-Prince.<\/p><\/div>\n<div id=\"attachment_2395\" style=\"width: 1034px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_258146.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2395\" class=\"wp-image-2395 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_258146.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_258146.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_258146-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2395\" class=\"wp-caption-text\">Dans le ventre d&#8217;un C-17 \u00e9quip\u00e9 pour le transport m\u00e9dical.<\/p><\/div>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h3>Sauvetage en mer<\/h3>\n<div id=\"attachment_3860\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-00165451.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3860\" class=\"wp-image-3860 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-00165451-1024x747.jpg\" alt=\"Le destroyer NCSM Athabaskan de la Marine Royale Canadienne dans les eaux des Cara\u00efbes au large d'Ha\u00efti. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\".\" width=\"1024\" height=\"747\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-00165451-1024x747.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-00165451-300x219.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-00165451-1080x788.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3860\" class=\"wp-caption-text\">Tournage sur le pont du NCSM Athabaskan. Image tir\u00e9e du film &#8220;Rescue&#8221;.<\/p><\/div>\n<div id=\"attachment_2347\" style=\"width: 1034px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX418720.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2347\" class=\"size-full wp-image-2347\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX418720.jpg\" alt=\"Tournage sur le pont du NCSM Athabaskan.\" width=\"1024\" height=\"679\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX418720.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX418720-300x199.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2347\" class=\"wp-caption-text\">Tournage sur le pont du NCSM Athabaskan.<\/p><\/div>\n<div id=\"attachment_1146\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G28_R.08934188.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1146\" class=\"wp-image-1146 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G28_R.08934188-1024x653.jpg\" alt=\"Le destroyer NCSM Athabaskan plonge dans une forte houle. De Rescue.\" width=\"1024\" height=\"653\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G28_R.08934188-1024x653.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G28_R.08934188-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G28_R.08934188-1080x689.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1146\" class=\"wp-caption-text\">Le destroyer NCSM Athabaskan plonge dans une forte houle. De Rescue. De <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_1139\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1139\" class=\"wp-image-1139 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G_24_2_0000019-1024x667.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"667\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G_24_2_0000019-1024x667.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G_24_2_0000019-300x196.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G_24_2_0000019-1080x704.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-1139\" class=\"wp-caption-text\">Le commandant Peter Crane et l&#8217;\u00e9quipage sur la passerelle du NCSM Athabaskan.<\/p><\/div>\n<div id=\"attachment_1940\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX38487.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1940\" class=\"wp-image-1940 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX38487-1024x679.jpg\" alt=\"prod-res-_LEX38487\" width=\"1024\" height=\"679\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX38487-1024x679.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX38487-300x199.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-_LEX38487-1080x716.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1940\" class=\"wp-caption-text\">Tournage du d\u00e9collage d&#8217;un h\u00e9licopt\u00e8re au-dessus du pont d&#8217;envol du NCSM Athabaskan.<\/p><\/div>\n<div id=\"attachment_1145\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G25_L.08096557.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1145\" class=\"wp-image-1145 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G25_L.08096557-1024x653.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"653\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G25_L.08096557-1024x653.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G25_L.08096557-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G25_L.08096557-1080x688.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1145\" class=\"wp-caption-text\">Image tir\u00e9e du film <em>Rescue<\/em>: un h\u00e9licopt\u00e8re Sea King atterrit sur le pont du destroyer de la Marine Royale Canadienne, le NCSM Athabascan.<\/p><\/div>\n<div id=\"attachment_3859\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3859\" class=\"wp-image-3859 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554-1024x683.jpg\" alt=\"Tournage d'une livraison d'eau .\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554-1024x683.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554-300x200.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554-1080x720.jpg 1080w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_0554.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3859\" class=\"wp-caption-text\">Tournage d&#8217;une livraison d&#8217;eau .<\/p><\/div>\n<div id=\"attachment_3863\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-racing-for-water101.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3863\" class=\"wp-image-3863 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-racing-for-water101-1024x652.jpg\" alt=\"Un h\u00e9licopt\u00e8re Sea King de la marine canadienne effectue une livraison d'eau en Ha\u00efti. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\".\" width=\"1024\" height=\"652\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-racing-for-water101-1024x652.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-racing-for-water101-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-racing-for-water101-1080x687.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3863\" class=\"wp-caption-text\">Un h\u00e9licopt\u00e8re Sea King de la marine canadienne effectue une livraison d&#8217;eau en Ha\u00efti. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant &#8220;Rescue&#8221;.<\/p><\/div>\n<div id=\"attachment_2403\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_304855.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2403\" class=\"wp-image-2403 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_304855.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_304855.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_304855-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2403\" class=\"wp-caption-text\"><strong>Tournage sur le pont du NCSM Athabaskan.<\/strong> La cam\u00e9ra 3D est pr\u00e9par\u00e9e pour le tournage \u00e0 l&#8217;aide d&#8217;une grue et d&#8217;un chariot. Le tournage \u00e0 l&#8217;aide d&#8217;une grue n&#8217;\u00e9tait pas possible sur l&#8217;oc\u00e9an et a \u00e9t\u00e9 r\u00e9serv\u00e9 \u00e0 un tournage sp\u00e9cial sur le port.<\/p><\/div>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_307356.jpg\"><img decoding=\"async\" class=\" size-full wp-image-2404 alignnone\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_307356.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_307356.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_307356-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<div id=\"attachment_1157-2\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1157-2\" class=\"wp-image-1157 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-1024x653.jpg\" alt=\"Commandant Peter Crane, Marine Royale du Canada\" width=\"1024\" height=\"653\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-1024x653.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G80L.95826829-1080x688.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1157-2\" class=\"wp-caption-text\">Commandant Peter Crane, Marine Royale du Canada<\/p><\/div>\n<div id=\"attachment_2407\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_316960.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2407\" class=\"wp-image-2407 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_316960.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_316960.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-IMG_316960-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-2407\" class=\"wp-caption-text\">Tournage \u00e0 bord d&#8217;un RIB ( (Bateau pneumatique \u00e0 coque rigide).<\/p><\/div>\n<div id=\"attachment_1158\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G81L.98297230.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1158\" class=\"wp-image-1158 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G81L.98297230-1024x652.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"652\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G81L.98297230-1024x652.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G81L.98297230-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G81L.98297230-1080x687.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1158\" class=\"wp-caption-text\">Une \u00e9quipe de la marine envoy\u00e9e par le NCSM Athabaskan. Image tir\u00e9e du film <em>Rescue<\/em>.<\/p><\/div>\n<div id=\"attachment_3862\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-orphanage-construct111.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3862\" class=\"wp-image-3862 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-orphanage-construct111-1024x653.jpg\" alt=\"Le personnel de la Marine canadienne construit des installations temporaires en Ha\u00efti. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\".\" width=\"1024\" height=\"653\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-orphanage-construct111-1024x653.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-orphanage-construct111-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-orphanage-construct111-1080x688.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3862\" class=\"wp-caption-text\">Le personnel de la Marine canadienne construit des installations temporaires pour dormir dans un orphelinat \u00e0 Jacmel, en Ha\u00efti. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant &#8220;Rescue&#8221;.<\/p><\/div>\n<div id=\"attachment_3861\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-kids91.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3861\" class=\"wp-image-3861 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-kids91-1024x652.jpg\" alt=\"Personnel de la Marine canadienne avec des orphelins ha\u00eftiens. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"652\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-kids91-1024x652.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-kids91-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-kids91-1080x687.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-3861\" class=\"wp-caption-text\">Personnel de la Marine canadienne avec des orphelins ha\u00eftiens. Image tir\u00e9e du film sur \u00e9cran g\u00e9ant &#8220;Rescue&#8221;<\/p><\/div>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h3>Sauvetage en h\u00e9licopt\u00e8re<\/h3>\n<div id=\"attachment_2379\" style=\"width: 691px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_15144.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-2379\" class=\"wp-image-2379 size-full\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_15144.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"681\" height=\"1024\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_15144.jpg 681w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_15144-200x300.jpg 200w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><\/a><p id=\"caption-attachment-2379\" class=\"wp-caption-text\">L&#8217;\u00e9quipe filme un exercice de sauvetage en montagne dans les montagnes de la Sierra Nevada.<\/p><\/div>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-2380 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141-681x1024.jpg\" alt=\"Cr\u00e9er Rescue 3D\" width=\"681\" height=\"1024\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141-681x1024.jpg 681w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141-199x300.jpg 199w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141-1080x1625.jpg 1080w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/prod-res-AIR-09.2010_228141.jpg 1695w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><\/a><\/p>\n<div id=\"attachment_1148\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G51L.008882820.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1148\" class=\"wp-image-1148 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G51L.008882820-1024x651.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"651\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G51L.008882820-1024x651.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G51L.008882820-300x191.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G51L.008882820-1080x687.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-1148\" class=\"wp-caption-text\">Exercice de sauvetage \u00e0 haute altitude avec un h\u00e9licopt\u00e8re Chinook \u00e0 double rotor au-dessus du lac Tahoe (altitude de 6 250 pieds) dans les montagnes de la Sierra Nevada. Image tir\u00e9e du film <em>Rescue<\/em>.<\/p><\/div>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G58L.032126122.jpg\"><img decoding=\"async\" class=\"alignnone wp-image-1150 size-large\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G58L.032126122-1024x654.jpg\" alt=\"Image tir\u00e9e du film sur \u00e9cran g\u00e9ant \"Rescue\"\" width=\"1024\" height=\"654\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G58L.032126122-1024x654.jpg 1024w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G58L.032126122-300x192.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-AIR_G58L.032126122-1080x690.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h2>&nbsp;R\u00e9sultats<\/h2>\n<p><em>Rescue<\/em> a \u00e9t\u00e9 projet\u00e9 dans le monde entier, offrant au public la premi\u00e8re vision sur \u00e9cran g\u00e9ant d&#8217;une catastrophe internationale en cours et un \u00e9chantillon de la diversit\u00e9 des formations, de la discipline et de l&#8217;engagement unique des intervenants. Le film a \u00e9t\u00e9 commercialis\u00e9 en collaboration avec la Croix-Rouge am\u00e9ricaine et le National Volunteer Fire Council (NVFC).<\/p>\n<p>Rescue est projet\u00e9 dans certains cin\u00e9mas \u00e0 \u00e9cran g\u00e9ant et est disponible en Blu-ray. Voir <a href=\"http:\/\/www.stephenlow.com\/where-to-see-rescue-3d\/\" target=\"_blank\" rel=\"noopener noreferrer\">&#8220;O\u00f9 voir <em>Rescue 3D<\/em>&#8220;<\/a>.<\/p>\n<p><a href=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-key-title.jpg\"><img decoding=\"async\" class=\"alignleft size-full wp-image-1656\" src=\"http:\/\/www.stephenlow.com\/wp-content\/uploads\/res-key-title.jpg\" alt=\"res-key-title\" width=\"1080\" height=\"540\" srcset=\"https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-key-title.jpg 1080w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-key-title-300x150.jpg 300w, https:\/\/www.stephenlow.com\/wp-content\/uploads\/res-key-title-1024x512.jpg 1024w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/p>\n<div style=\"clear: both;\">&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/div>\n<h2>Liens<\/h2>\n<p>Visitez le site officiel du film <em>Rescue <\/em>: <a href=\"http:\/\/www.rescue-film.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.rescue-film.com<\/a><\/p>\n<p><strong>La Croix-Rouge am\u00e9ricaine<\/strong><br \/>\nLa Croix-Rouge am\u00e9ricaine h\u00e9berge, nourrit et apporte un soutien \u00e9motionnel aux victimes de catastrophes ; elle fournit pr\u00e8s de la moiti\u00e9 du sang du pays ; elle enseigne les gestes qui sauvent ; elle fournit une aide humanitaire internationale ; et elle soutient les membres des forces arm\u00e9es et leurs familles. La Croix-Rouge est une organisation caritative et non une agence gouvernementale et elle d\u00e9pend des b\u00e9n\u00e9voles et de la g\u00e9n\u00e9rosit\u00e9 du public am\u00e9ricain pour mener \u00e0 bien sa mission. Pour plus d&#8217;informations, veuillez consulter le site <a href=\"http:\/\/www.redcross.org\" target=\"_blank\" rel=\"noopener noreferrer\">www.redcross.org<\/a>.<\/p>\n<p>Dix cents de chaque billet Rescue vendu ont \u00e9t\u00e9 affect\u00e9s au &nbsp;soutien de l&#8217;American Red Cross Disaster Relief afin d&#8217;aider les personnes touch\u00e9es par une catastrophe dans le monde entier.<\/p>\n<p><strong>Le Conseil national des sapeurs-pompiers volontaires (NVFC)<\/strong><br \/>\nLe National Volunteer Fire Council (NVFC) est la principale association \u00e0 but non lucratif repr\u00e9sentant les int\u00e9r\u00eats des pompiers volontaires, des services m\u00e9dicaux d&#8217;urgence et des services de secours. Le NVFC est la voix des volontaires au niveau national et fournit des outils, des ressources, des programmes et des services de d\u00e9fense inestimables pour les premiers intervenants dans tout le pays. Pour en savoir plus, consultez le site <a href=\"http:\/\/www.nvfc.org\" target=\"_blank\" rel=\"noopener noreferrer\">www.nvfc.org.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Film\u00e9 pour \u00eatre pr\u00e9sent\u00e9 en IMAX 3D et 2D, Rescue plonge le public dans le travail difficile, mais inspirant, qui consiste \u00e0 sauver des vies face \u00e0 une catastrophe naturelle. Ce projet de documentaire est parti d&#8217;une approche simple, bien que difficile : suivre la formation d&#8217;individus \u00e0 l&#8217;intervention en cas de catastrophe, puis les suivre lorsqu&#8217;ils interviennent lors d&#8217;une v\u00e9ritable catastrophe. <\/p>\n","protected":false},"author":5,"featured_media":14691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[115],"tags":[116],"class_list":["post-15788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-revue","tag-rescue-fr"],"_links":{"self":[{"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/posts\/15788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/comments?post=15788"}],"version-history":[{"count":0,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/posts\/15788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/media\/14691"}],"wp:attachment":[{"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/media?parent=15788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/categories?post=15788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stephenlow.com\/fr\/wp-json\/wp\/v2\/tags?post=15788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}